{"id":437,"count":1,"description":"","link":"http:\/\/tmproperty.marketing.co.th\/zh-hans\/category\/%e5%b7%a5%e5%8e%82%e5%92%8c%e4%bb%93%e5%ba%93\/","name":"\u5de5\u5382\u548c\u4ed3\u5e93","slug":"%e5%b7%a5%e5%8e%82%e5%92%8c%e4%bb%93%e5%ba%93","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/tmproperty.marketing.co.th\/zh-hans\/wp-json\/wp\/v2\/categories\/437"}],"collection":[{"href":"http:\/\/tmproperty.marketing.co.th\/zh-hans\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/tmproperty.marketing.co.th\/zh-hans\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/tmproperty.marketing.co.th\/zh-hans\/wp-json\/wp\/v2\/posts?categories=437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}